{"id":90242,"date":"2021-01-07T13:01:30","date_gmt":"2021-01-07T09:31:30","guid":{"rendered":"https:\/\/tarikhema.org\/info\/?p=90242"},"modified":"2020-09-16T13:02:49","modified_gmt":"2020-09-16T08:32:49","slug":"%da%86%d9%87-%d9%85%d8%a7%d9%87%db%8c-%d8%a8%d8%a7%d8%b1%d8%af%d8%a7%d8%b1-%d8%b4%d9%88%db%8c%d9%85-%d8%aa%d8%a7-%d9%be%d8%b3%d8%b1-%d8%b4%d9%88%d8%af%d8%9f","status":"publish","type":"post","link":"https:\/\/tarikhema.org\/info\/90242\/%da%86%d9%87-%d9%85%d8%a7%d9%87%db%8c-%d8%a8%d8%a7%d8%b1%d8%af%d8%a7%d8%b1-%d8%b4%d9%88%db%8c%d9%85-%d8%aa%d8%a7-%d9%be%d8%b3%d8%b1-%d8%b4%d9%88%d8%af%d8%9f\/","title":{"rendered":"\u0686\u0647 \u0645\u0627\u0647\u06cc \u0628\u0627\u0631\u062f\u0627\u0631 \u0634\u0648\u06cc\u0645 \u062a\u0627 \u067e\u0633\u0631 \u0634\u0648\u062f\u061f"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>\u0641\u0627\u06a9\u062a\u0648\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0631 \u0631\u0648\u06cc\u00a0<strong><a class=\"rl\" title=\"\u0631\u0648\u0634 \u062a\u0639\u06cc\u06cc\u0646 \u062c\u0646\u0633\u06cc\u062a\" href=\"https:\/\/namnak.com\/%D8%AA%D8%B9%DB%8C%DB%8C%D9%86-%D8%AC%D9%86%D8%B3%DB%8C%D8%AA-%D8%AC%D9%86%DB%8C%D9%86.p11295\" target=\"_blank\" rel=\"noopener noreferrer\">\u062a\u0639\u06cc\u06cc\u0646 \u062c\u0646\u0633\u06cc\u062a<\/a><\/strong>\u00a0\u0627\u062b\u0631 \u06af\u0630\u0627\u0631 \u0627\u0633\u062a . \u0627\u06af\u0631 \u0634\u0645\u0627 \u0645\u0627\u06cc\u0644\u06cc\u062f \u067e\u0633\u0631 \u062f\u0627\u0631 \u0634\u0648\u06cc\u062f \u060c \u0631\u0648\u0634 \u0647\u0627\u06cc \u062e\u0627\u0635 \u0648 \u0645\u0637\u0645\u0626\u0646\u06cc \u0628\u0631\u0627\u06cc\u00a0<strong><a class=\"rl\" title=\"\u0631\u0627\u0647 \u0647\u0627\u06cc \u067e\u0633\u0631 \u062f\u0627\u0631 \u0634\u062f\u0646\" href=\"https:\/\/namnak.com\/%D9%BE%D8%B3%D8%B1-%D8%AF%D8%A7%D8%B1-%D8%B4%D8%AF%D9%86.p69776\" target=\"_blank\" rel=\"noopener noreferrer\">\u067e\u0633\u0631 \u062f\u0627\u0631 \u0634\u062f\u0646<\/a><\/strong>\u00a0\u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0628\u0631\u0627\u06cc\u00a0<strong><a class=\"rl\" title=\"\u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646\" href=\"https:\/\/namnak.com\/%D9%BE%D8%B3%D8%B1-%D8%B4%D8%AF%D9%86-%D8%AC%D9%86%DB%8C%D9%86.p30634\" target=\"_blank\" rel=\"noopener noreferrer\">\u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646<\/a><\/strong>\u00a0\u0646\u0648\u0639 \u062a\u063a\u0630\u06cc\u0647 \u0634\u0645\u0627 \u0648 \u0647\u0645\u0633\u0631\u062a\u0627\u0646 \u0648 \u0627\u0642\u062f\u0627\u0645 \u0628\u0647\u00a0<em>\u0628\u0627\u0631\u062f\u0627\u0631\u06cc<\/em>\u00a0\u062f\u0631 \u0641\u0635\u0644 \u0648 \u0634\u0631\u0627\u06cc\u0637 \u062e\u0627\u0635 \u0628\u06cc \u062a\u0627\u062b\u06cc\u0631 \u0646\u06cc\u0633\u062a . \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0631\u0627\u0647\u06cc \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u0627\u0646\u0633\u00a0<strong><a class=\"rl\" title=\"\u0631\u0627\u0647 \u0647\u0627\u06cc \u067e\u0633\u0631\u062f\u0627\u0631 \u0634\u062f\u0646\" href=\"https:\/\/namnak.com\/%D9%BE%D8%B3%D8%B1-%D8%AF%D8%A7%D8%B1-%D8%B4%D8%AF%D9%86.p69776\" target=\"_blank\" rel=\"noopener noreferrer\">\u067e\u0633\u0631\u062f\u0627\u0631 \u0634\u062f\u0646<\/a><\/strong>\u00a0\u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u06cc\u0646 \u0628\u062e\u0634 \u0627\u0632\u00a0<strong><a class=\"rl\" title=\"\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0647\u0641\u062a\u0647 \u0628\u0647 \u0647\u0641\u062a\u0647 \u0628\u0631\u0627\u06cc 9 \u0645\u0627\u0647\" href=\"https:\/\/namnak.com\/%D8%A8%D8%A7%D8%B1%D8%AF%D8%A7%D8%B1%DB%8C-%D9%87%D9%81%D8%AA%D9%87-%D8%A8%D9%87-%D9%87%D9%81%D8%AA%D9%87.p26\" target=\"_blank\" rel=\"noopener noreferrer\">\u0628\u0627\u0631\u062f\u0627\u0631\u06cc<\/a><\/strong>\u00a0<strong><a class=\"rl\" title=\"\" href=\"https:\/\/namnak.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u0646\u0645\u0646\u0627\u06a9<\/a><\/strong>\u00a0\u0631\u0648\u0634 \u0647\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u0627\u0646\u0633\u00a0<em>\u067e\u0633\u0631\u062f\u0627\u0631 \u0634\u062f\u0646<\/em>\u00a0\u062e\u0627\u0646\u0645 \u0647\u0627 \u0631\u0627 \u0628\u0647 \u0634\u0645\u0627 \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc \u06a9\u0646\u062f.\u0686\u0647 \u0686\u06cc\u0632\u0647\u0627\u06cc\u06cc \u0645\u0648\u062c\u0628 \u067e\u0633\u0631 \u0634\u062f\u0646\u00a0<em>\u062c\u0646\u06cc\u0646<\/em>\u00a0\u0645\u06cc \u0634\u0648\u062f\u061f<strong>\u0632\u0646\u062f\u06af\u06cc \u0628\u0627 \u0647\u0645\u0633\u0631 \u062f\u0631 \u06cc\u06a9 \u0645\u06a9\u0627\u0646<\/strong><\/p>\n<div>\n<map name=\"cnc\">\n<area alt=\"\u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646\" coords=\"0,0,600,400\" shape=\"rect\" href=\"https:\/\/namnak.com\/%D9%BE%D8%B3%D8%B1-%D8%B4%D8%AF%D9%86-%D8%AC%D9%86%DB%8C%D9%86.p30634\" \/><\/map>\n<\/div>\n<p>\u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0627\u0646\u062c\u0627\u0645 \u0634\u062f\u0647 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0632\u0648\u062c\u06cc\u0646\u06cc \u06a9\u0647 \u067e\u0633 \u0627\u0632 \u0627\u0632\u062f\u0648\u0627\u062c \u0628\u0627 \u0647\u0645 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f \u060c \u0627\u062d\u062a\u0645\u0627\u0644\u00a0<em>\u067e\u0633\u0631 \u062f\u0627\u0631 \u0634\u062f\u0646<\/em>\u0634\u0627\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0627\u0633\u062a \u060c \u0639\u0644\u062a \u0627\u062d\u062a\u0645\u0627\u0644\u00a0<em>\u067e\u0633\u0631 \u062f\u0627\u0631 \u0634\u062f\u0646<\/em>\u00a0\u0627\u06cc\u0646 \u0632\u0648\u062c\u06cc\u0646 \u0647\u0646\u0648\u0632 \u0646\u0627 \u0645\u0634\u062e\u0635 \u0627\u0633\u062a.<\/p>\n<p class=\"tcr\">\u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc\u00a0<em>\u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646<\/em><\/p>\n<h3>\u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646 \u0628\u0627 \u0645\u0648\u062b\u0631\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u0647\u0627<\/h3>\n<p><strong>\u0627\u0642\u062f\u0627\u0645 \u0628\u0647\u00a0<a class=\"rl\" title=\"\u0632\u0645\u0627\u0646 \u0628\u0627\u0631\u062f\u0627\u0631 \u0634\u062f\u0646 \u0628\u0639\u062f \u0627\u0632 \u0646\u0632\u062f\u06cc\u06a9\u06cc\" href=\"https:\/\/namnak.com\/%D8%A8%D8%A7%D8%B1%D8%AF%D8%A7%D8%B1-%D8%B4%D8%AF%D9%86.p40792\" target=\"_blank\" rel=\"noopener noreferrer\">\u0628\u0627\u0631\u062f\u0627\u0631 \u0634\u062f\u0646<\/a>\u00a0\u062f\u0631 \u0627\u0648\u0627\u06cc\u0644 \u0627\u0632\u062f\u0648\u0627\u062c<\/strong><\/p>\n<p>\u0627\u06af\u0631 \u062a\u0627\u0632\u0647 \u0627\u0632\u062f\u0648\u0627\u062c \u06a9\u0631\u062f\u0647 \u0627\u06cc\u062f \u0648 \u0627\u0648\u0627\u06cc\u0644 \u0634\u0631\u0648\u0639 \u0631\u0627\u0628\u0637\u0647 \u0634\u0645\u0627 \u0627\u0633\u062a \u060c \u0627\u062d\u062a\u0645\u0627\u0644\u0627 \u0633\u06a9\u0633 \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0631\u06cc\u062f \u0648 \u0633\u06a9\u0633 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0633\u067e\u0631\u0645\u062a\u0627\u0646 \u0631\u0627 \u0641\u0639\u0627\u0644\u062a\u0631 \u0645\u06cc \u06a9\u0646\u062f \u0632\u06cc\u0631\u0627\u00a0<strong><a class=\"rl\" title=\"\u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0633\u067e\u0631\u0645\" href=\"https:\/\/namnak.com\/%D8%A7%D8%B3%D9%BE%D8%B1%D9%85-%D8%B2%DB%8C%D8%A7%D8%AF-%DA%A9%D9%86-%D9%82%D9%88%DB%8C.p31408\" target=\"_blank\" rel=\"noopener noreferrer\">\u0627\u0633\u067e\u0631\u0645<\/a><\/strong>\u00a0\u0633\u0628\u06a9 \u0627\u0633\u062a \u0648 \u0633\u0631 \u06a9\u0648\u0686\u06a9 \u0648 \u062f\u0645 \u06a9\u0648\u062a\u0627\u0647\u06cc \u062f\u0627\u0631\u062f\u0648 \u062d\u062a\u06cc \u0628\u0627 \u0648\u062c\u0648\u062f \u0645\u0648\u06a9\u0648\u0633 \u06a9\u0645 \u062f\u0631 \u0648\u0627\u0698\u0646 \u062f\u0631 \u0634\u0631\u0648\u0639 \u0646\u0632\u062f\u06cc\u06a9\u06cc\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u062a\u062e\u0645\u06a9 \u0628\u0631\u0633\u0627\u0646\u062f \u0648 \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0648 \u0627\u0646\u062a\u0647\u0627\u06cc \u0628\u0627\u0631\u0648\u0631\u06cc \u0634\u0645\u0627 \u0642\u062f\u0631\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<p><strong>\u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0627\u0644\u0631\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0628\u0631\u0627\u06cc \u067e\u0633\u0631 \u062f\u0627\u0631 \u0634\u062f\u0646<\/strong><\/p>\n<p>\u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0635\u0648\u0631\u062a \u06af\u0631\u0641\u062a\u0647 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0632\u0646\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0627\u0644\u0627\u062a\u0631\u06cc\u0646 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0627\u0644\u0631\u06cc \u062f\u0631 \u0631\u0648\u0632 \u0631\u0627 \u062f\u0627\u0634\u062a\u0646\u062f \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0632\u0646\u0627\u0646\u06cc \u06a9\u0647 \u06a9\u0627\u0644\u0631\u06cc \u06a9\u0645\u062a\u0631\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0631\u062f\u0646\u062f \u0628\u0647 \u0627\u062d\u062a\u0645\u0627\u0644 \u0628\u06cc\u0634\u062a\u0631\u06cc \u067e\u0633\u0631 \u062f\u0627\u0631 \u0645\u06cc \u0634\u0648\u0646\u062f.<\/p>\n<p>\u0645\u0637\u0627\u0644\u0639\u0647 \u062f\u06cc\u06af\u0631 \u0628\u0631 \u0631\u0648\u06cc \u0632\u0646\u0627\u0646 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0632\u0646\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u0637\u06cc\u00a0<strong><a class=\"rl\" title=\"\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0647\u0641\u062a\u0647 \u0628\u0647 \u0647\u0641\u062a\u0647 + \u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u062c\u0646\u06cc\u0646\" href=\"https:\/\/namnak.com\/%D8%A8%D8%A7%D8%B1%D8%AF%D8%A7%D8%B1%DB%8C-%D9%87%D9%81%D8%AA%D9%87-%D8%A8%D9%87-%D9%87%D9%81%D8%AA%D9%87.p26\" target=\"_blank\" rel=\"noopener noreferrer\">\u062f\u0648\u0631\u0627\u0646 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc<\/a><\/strong>\u00a0\u062f\u0686\u0627\u0631 \u0627\u0636\u0627\u0641\u0647 \u0648\u0632\u0646 \u0634\u062f\u0647 \u0627\u0646\u062f \u060c \u062a\u0642\u0631\u06cc\u0628\u0627 \u067e\u0633\u0631\u062f\u0627\u0631 \u0634\u062f\u0646\u062f \u0632\u06cc\u0631\u0627 \u062c\u0646\u06cc\u0646 \u067e\u0633\u0631 \u062d\u0633\u0627\u0633 \u062a\u0631 \u0627\u0633\u062a \u0648 \u0628\u0627 \u0630\u062e\u0627\u06cc\u0631 \u06a9\u0645 \u063a\u0630\u0627\u06cc\u06cc \u0646\u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0632\u0646\u062f\u0647 \u0628\u0645\u0627\u0646\u062f \u0648 \u0631\u0634\u062f \u06a9\u0646\u062f \u0627\u0645\u0627 \u062c\u0646\u06cc\u0646 \u062f\u062e\u062a\u0631 \u0642\u0648\u06cc\u062a\u0631 \u0628\u0648\u062f\u0647 \u0628\u0627 \u0630\u062e\u0627\u06cc\u0631 \u0627\u0646\u062f\u06a9 \u0647\u0645 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0632\u0646\u062f\u0647 \u0628\u0645\u0627\u0646\u062f.<\/p>\n<p><strong>\u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u062f\u0631 \u0641\u0635\u0644 \u062a\u0627\u0628\u0633\u062a\u0627\u0646<\/strong><\/p>\n<p>\u0628\u06cc\u0634\u062a\u0631 \u067e\u0633\u0631\u0647\u0627 \u0645\u062a\u0648\u0644\u062f \u062a\u0627\u0628\u0633\u062a\u0627\u0646 \u0648 \u0627\u063a\u0644\u0628 \u062f\u062e\u062a\u0631\u0647\u0627 \u0645\u062a\u0648\u0644\u062f \u0632\u0645\u0633\u062a\u0627\u0646\u0646\u062f \u0632\u06cc\u0631\u0627 \u062c\u0646\u06cc\u0646 \u067e\u0633\u0631 \u062d\u0633\u0627\u0633 \u062a\u0631 \u0627\u0632 \u062c\u0646\u06cc\u0646 \u062f\u062e\u062a\u0631 \u0628\u0648\u062f\u0647 \u0648 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0648\u062c\u0648\u062f \u0628\u0627\u06a9\u062a\u0631\u06cc \u0647\u0627 \u0648 \u0648\u06cc\u0631\u0648\u0633 \u0647\u0627\u06cc \u0639\u0641\u0648\u0646\u06cc \u062f\u0631 \u0641\u0635\u0644 \u0632\u0645\u0633\u062a\u0627\u0646 \u0646\u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0632\u0646\u062f\u0647 \u0628\u0645\u0627\u0646\u062f.<\/p>\n<h4 class=\"tcr\">\u0631\u0627\u0647 \u0647\u0627\u06cc \u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646<\/h4>\n<h3>\u0639\u0648\u0627\u0645\u0644 \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u062f\u0631 \u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646<\/h3>\n<h4><strong><a class=\"rl\" title=\"\u062f\u0631\u0645\u0627\u0646 \u062f\u06cc\u0627\u0628\u062a\" href=\"https:\/\/namnak.com\/%D8%B4%D8%A7%D8%AE-%D8%BA%D9%88%D9%84-%D8%AF%DB%8C%D8%A7%D8%A8%D8%AA.p35131\" target=\"_blank\" rel=\"noopener noreferrer\">\u062f\u06cc\u0627\u0628\u062a<\/a><\/strong>\u00a0\u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0648 \u0627\u0631\u062a\u0628\u0627\u0637 \u0622\u0646 \u0628\u0627 \u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646<\/h4>\n<p>\u0645\u0627\u062f\u0631\u0627\u0646 \u062f\u0627\u0631\u0627\u06cc \u062c\u0646\u06cc\u0646 \u067e\u0633\u0631 \u0628\u0647 \u0627\u062d\u062a\u0645\u0627\u0644 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0645\u0628\u062a\u0644\u0627 \u0628\u0647\u00a0<em>\u062f\u06cc\u0627\u0628\u062a<\/em>\u00a0\u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u062e\u0648\u0627\u0647\u0646\u062f \u0634\u062f \u0632\u06cc\u0631\u0627 \u0627\u062d\u062a\u0645\u0627\u0644\u0627 \u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646 \u0628\u0627 \u0639\u0645\u0644\u06a9\u0631\u062f \u0633\u0644\u0648\u0644 \u0647\u0627\u06cc \u0645\u062a\u0627\u062b\u0631 \u0627\u0632 \u0645\u062a\u0627\u0628\u0648\u0644\u06cc\u0633\u0645 \u06af\u0644\u0648\u06a9\u0632 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627\u0634\u062f.<\/p>\n<p><strong>\u0622\u0645\u06cc\u0632\u0634 \u062f\u0631 \u062f\u0648\u0631\u0647\u00a0<a class=\"rl\" title=\"\u0639\u0644\u0627\u0626\u0645 \u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc\" href=\"https:\/\/namnak.com\/%D9%86%D8%B4%D8%A7%D9%86%D9%87-%D9%87%D8%A7%DB%8C-%D8%AA%D8%AE%D9%85%DA%A9-%DA%AF%D8%B0%D8%A7%D8%B1%DB%8C.p35046\" target=\"_blank\" rel=\"noopener noreferrer\">\u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc<\/a><\/strong><\/p>\n<p>\u0631\u062d\u0645 \u062f\u0631 \u062f\u0648\u0631\u0647\u00a0<em>\u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc<\/em>\u00a0\u0645\u062d\u06cc\u0637\u06cc \u0642\u0644\u06cc\u0627\u06cc\u06cc \u0648 \u0645\u06cc\u0632\u0627\u0646 PH \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f \u0648 \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0644\u0642\u0627\u062d \u0627\u0646\u062c\u0627\u0645 \u06af\u06cc\u0631\u062f \u0627\u062d\u062a\u0645\u0627\u0644 \u067e\u0633\u0631 \u062f\u0627\u0631 \u0634\u062f\u0646 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0633\u062a. \u0645\u062d\u06cc\u0637 \u0642\u0644\u06cc\u0627\u06cc\u06cc\u060c \u0628\u0631\u0627\u06cc \u0631\u0634\u062f \u0648 \u0628\u0642\u0627\u06cc\u00a0<em>\u0627\u0633\u067e\u0631\u0645<\/em>\u00a0\u0647\u0627\u06cc \u0645\u0631\u062f\u0627\u0646\u0647 \u0645\u062b\u0644 \u06a9\u0631\u0648\u0645\u0648\u0632\u0648\u0645 Y \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a. \u0628\u0627 \u062e\u0631\u06cc\u062f\u0646 \u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc PH \u0627\u0632 \u062f\u0627\u0631\u0648\u062e\u0627\u0646\u0647 \u0647\u0627 \u067e\u06cc \u0628\u0628\u0631\u06cc\u062f \u06a9\u0647 \u0645\u062d\u06cc\u0637 \u0628\u062f\u0646 \u0648 \u0628\u0647 \u062e\u0635\u0648\u0635 \u0646\u0627\u062d\u06cc\u0647 \u062a\u0646\u0627\u0633\u0644\u06cc \u0634\u0645\u0627 \u0642\u0644\u06cc\u0627\u06cc\u06cc \u0627\u0633\u062a \u06cc\u0627 \u0627\u0633\u06cc\u062f\u06cc\u061f<\/p>\n<p><strong>\u0631\u0633\u06cc\u062f\u0646 \u0628\u0647 \u062d\u0627\u0644\u062a \u0627\u0631\u06af\u0627\u0633\u0645<\/strong><\/p>\n<p>\u0631\u0633\u06cc\u062f\u0646 \u0628\u0647 \u0627\u0648\u062c\u00a0<strong><a class=\"rl\" title=\"\u0627\u0641\u0632\u0627\u06cc\u0634 \u0644\u0630\u062a \u062c\u0646\u0633\u06cc\" href=\"https:\/\/namnak.com\/%D9%84%D8%B0%D8%AA-%D8%AC%D9%86%D8%B3%DB%8C.p19127\" target=\"_blank\" rel=\"noopener noreferrer\">\u0644\u0630\u062a \u062c\u0646\u0633\u06cc<\/a><\/strong>\u00a0\u0628\u0631\u0627\u06cc \u062e\u0627\u0646\u0645 \u0647\u0627 \u062f\u0631 \u0627\u06cc\u062c\u0627\u062f \u0645\u062d\u06cc\u0637 \u0642\u0644\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u0628\u062f\u0646 \u0632\u0646\u0627\u0646\u060c \u0628\u0633\u06cc\u0627\u0631 \u0645\u0648\u062b\u0631 \u0627\u0633\u062a \u0648 \u0628\u0647 \u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646 \u06a9\u0645\u06a9 \u0632\u06cc\u0627\u062f\u06cc \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<h4 class=\"tcr\">\u0646\u06a9\u0627\u062a \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646<\/h4>\n<h3>\u06a9\u062f\u0627\u0645 \u0632\u0646 \u0647\u0627 \u067e\u0633\u0631 \u0632\u0627 \u0647\u0633\u062a\u0646\u062f\u061f<\/h3>\n<p>\u0628\u0647 \u063a\u06cc\u0631 \u0627\u0632 \u0646\u0648\u0639 \u062a\u063a\u0630\u06cc\u0647 \u0639\u0648\u0627\u0645\u0644 \u062f\u06cc\u06af\u0631\u06cc \u0646\u06cc\u0632 \u062f\u0631 \u067e\u0633\u0631\u062f\u0627\u0631 \u0634\u062f\u0646 \u062a\u0627\u062b\u06cc\u0631 \u062f\u0627\u0631\u062f . \u0632\u0646\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0639\u062f \u0627\u0632 \u062a\u0635\u0645\u06cc\u0645 \u0628\u0647 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc\u060c \u06cc\u06a9 \u0633\u0627\u0644 \u06cc\u0627 \u0628\u06cc\u0634\u062a\u0631 \u062f\u0686\u0627\u0631 \u062a\u0627\u062e\u06cc\u0631 \u062f\u0631 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0645\u06cc \u0634\u0648\u0646\u062f \u060c \u0627\u062d\u062a\u0645\u0627\u0644 \u0627\u06cc\u0646 \u06a9\u0647 \u0635\u0627\u062d\u0628 \u0641\u0631\u0632\u0646\u062f \u067e\u0633\u0631 \u0634\u0648\u0646\u062f \u0628\u06cc\u0634\u062a\u0631 \u0627\u0633\u062a \u0632\u06cc\u0631\u0627 \u062f\u0631 \u062a\u0631\u0634\u062d\u0627\u062a \u063a\u0644\u06cc\u0638 \u06af\u0631\u062f\u0646 \u0631\u062d\u0645 \u0642\u062f\u0631\u062a \u0627\u0633\u067e\u0631\u0645 \u0647\u0627\u06cc \u062f\u0627\u0631\u0627\u06cc \u06a9\u0631\u0648\u0645\u0648\u0632\u0645 Y\u060c \u0627\u0632\u00a0<em>\u0627\u0633\u067e\u0631\u0645<\/em>\u00a0\u0647\u0627\u06cc \u062d\u0627\u0648\u06cc \u06a9\u0631\u0648\u0645\u0648\u0632\u0645 X \u0628\u06cc\u0634\u062a\u0631 \u0627\u0633\u062a. \u0627\u06af\u0631 \u0645\u06cc\u0632\u0627\u0646 \u062a\u0631\u0634\u062d\u0627\u062a \u06af\u0631\u062f\u0646 \u0631\u062d\u0645 \u063a\u0644\u06cc\u0638 \u062a\u0631 \u0628\u0627\u0634\u062f \u0627\u062d\u062a\u0645\u0627\u0644 \u0628\u0627\u0631\u0648\u0631\u06cc \u0648 \u062d\u0627\u0645\u0644\u06af\u06cc \u06a9\u0645\u062a\u0631 \u062e\u0648\u0627\u0647\u062f \u0634\u062f.<\/p>\n<h3><span style=\"color: #ff0000;\">\u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc\u00a0<\/span>\u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646<\/h3>\n<p><strong>\u0645\u0635\u0631\u0641 \u063a\u0630\u0627 \u0647\u0627\u06cc \u062f\u0627\u0631\u0627\u06cc \u0633\u062f\u06cc\u0645 \u0648\u00a0<a class=\"rl\" title=\"\u0645\u0646\u0627\u0628\u0639 \u067e\u062a\u0627\u0633\u06cc\u0645\" href=\"https:\/\/namnak.com\/%D8%AE%D9%88%D8%B1%D8%A7%DA%A9%DB%8C-%D9%87%D8%A7%DB%8C-%D8%B3%D8%B1%D8%B4%D8%A7%D8%B1-%D8%A7%D8%B2-%D9%BE%D8%AA%D8%A7%D8%B3%DB%8C%D9%85.p4197\" target=\"_blank\" rel=\"noopener noreferrer\">\u067e\u062a\u0627\u0633\u06cc\u0645<\/a><\/strong><\/p>\n<p>\u062f\u0631 \u0628\u062e\u0634 \u0647\u0627\u06cc \u0642\u0628\u0644\u06cc \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0648 \u0646\u0648\u0632\u0627\u062f \u062f\u0631\u00a0<em>\u0646\u0645\u0646\u0627\u06a9<\/em>\u00a0\u06a9\u0627\u0645\u0644 \u062a\u0648\u0636\u06cc\u062d \u062f\u0627\u062f\u06cc\u0645 \u06a9\u0647 \u062f\u0631\u00a0<strong><a class=\"rl\" title=\"\u062a\u0639\u06cc\u06cc\u0646 \u062c\u0646\u0633\u06cc\u062a \u062c\u0646\u06cc\u0646 \u0628\u062f\u0648\u0646 \u0633\u0648\u0646\u0648\u06af\u0631\u0627\u0641\u06cc\" href=\"https:\/\/namnak.com\/%D8%AA%D8%B9%DB%8C%DB%8C%D9%86-%D8%AC%D9%86%D8%B3%DB%8C%D8%AA-%D8%AC%D9%86%DB%8C%D9%86.p11295\" target=\"_blank\" rel=\"noopener noreferrer\">\u062a\u0639\u06cc\u06cc\u0646 \u062c\u0646\u0633\u06cc\u062a \u062c\u0646\u06cc\u0646<\/a><\/strong>\u00a0\u06cc\u0648\u0646 \u0647\u0627\u06cc \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0633\u062f\u06cc\u0645\u060c\u00a0<em>\u067e\u062a\u0627\u0633\u06cc\u0645<\/em>\u00a0\u0646\u0642\u0634 \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0631\u0646\u062f. \u0632\u0646\u0627\u0646\u06cc \u06a9\u0647 \u0645\u0627\u06cc\u0644\u0646\u062f \u067e\u0633\u0631\u062f\u0627\u0631 \u0634\u0648\u0646\u062f \u0628\u0627\u06cc\u062f \u0628\u06cc\u0634 \u0627\u0632 \u0647\u0631 \u0645\u0627\u062f\u0647 \u063a\u0630\u0627\u06cc\u06cc \u062f\u06cc\u06af\u0631\u06cc\u060c \u063a\u0630\u0627 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0633\u062f\u06cc\u0645 \u0648\u00a0<em>\u067e\u062a\u0627\u0633\u06cc\u0645<\/em>\u00a0\u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f \u0631\u0627 \u0645\u0635\u0631\u0641 \u06a9\u0646\u0646\u062f.<\/p>\n<p>\u0646\u0645\u06a9\u060c \u0633\u0631\u0634\u0627\u0631 \u0627\u0632 \u0633\u062f\u06cc\u0645 \u0627\u0633\u062a \u067e\u0633 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062e\u0627\u0646\u0645 \u0647\u0627 \u062f\u0631 \u062a\u0647\u06cc\u0647 \u063a\u0630\u0627\u060c \u062e\u0648\u0631\u062f\u0646 \u0645\u06cc\u0648\u0647 \u0647\u0627 \u0648 \u0633\u0627\u0644\u0627\u062f \u0627\u0632\u00a0<strong><a class=\"rl\" title=\"\u062e\u0648\u0627\u0635 \u0646\u0645\u06a9\" href=\"https:\/\/namnak.com\/salt-health-benefits.p48896\" target=\"_blank\" rel=\"noopener noreferrer\">\u0646\u0645\u06a9<\/a><\/strong>\u00a0\u0628\u06cc\u0634\u062a\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u0646\u062f \u0648\u00a0<strong><a class=\"rl\" title=\"\u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0645\u0641\u06cc\u062f\" href=\"https:\/\/namnak.com\/Food-industry.p16005\" target=\"_blank\" rel=\"noopener noreferrer\">\u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc<\/a><\/strong>\u00a0\u0634\u0648\u0631 \u0645\u0627\u0646\u0646\u062f \u0628\u06cc\u0633\u06a9\u0648\u06cc\u06cc\u062a \u0647\u0627\u06cc \u0634\u0648\u0631\u060c \u062a\u0631\u0634\u06cc\u060c \u0632\u06cc\u062a\u0648\u0646 \u0634\u0648\u0631\u0648 &#8230; \u0645\u0635\u0631\u0641 \u06a9\u0646\u0646\u062f.<\/p>\n<p>\u0627\u0645\u0627 \u0645\u0635\u0631\u0641 \u0632\u06cc\u0627\u062f\u00a0<em>\u0646\u0645\u06a9<\/em>\u00a0\u0633\u0628\u0628 \u0628\u0627\u0644\u0627 \u0631\u0641\u062a\u0646\u00a0<strong><a class=\"rl\" title=\"\u062f\u0631\u0645\u0627\u0646 \u0641\u0634\u0627\u0631 \u062e\u0648\u0646\" href=\"https:\/\/namnak.com\/%D9%81%D8%B4%D8%A7%D8%B1-%D8%AE%D9%88%D9%86.p12595\" target=\"_blank\" rel=\"noopener noreferrer\">\u0641\u0634\u0627\u0631 \u062e\u0648\u0646<\/a><\/strong>\u00a0\u0648 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u06cc \u0642\u0644\u0628\u06cc \u0645\u06cc \u0634\u0648\u062f \u067e\u0633 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062e\u0627\u0646\u0645 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0686\u0627\u0631 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u06cc \u0642\u0644\u0628\u06cc \u0647\u0633\u062a\u0646\u062f \u0627\u0632 \u0645\u0635\u0631\u0641\u00a0<em>\u0646\u0645\u06a9<\/em>\u00a0\u062e\u0648\u062f \u062f\u0627\u0631\u06cc \u0646\u0645\u0627\u06cc\u0646\u062f.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0645\u0627\u0646\u062f\u0646 \u0627\u0633\u067e\u0631\u0645 \u0647\u0627 \u062f\u0631 \u0631\u062d\u0645 \u062e\u0627\u0646\u0645 \u0647\u0627 \u0628\u0627\u06cc\u062f \u0632\u0648\u062c\u06cc\u0646\u00a0<em>\u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc<\/em>\u00a0\u062f\u0627\u0631\u0627\u06cc \u067e\u062a\u0627\u0633\u06cc\u0645 \u0641\u0631\u0627\u0648\u0627\u0646 \u0645\u0627\u0646\u0646\u062f \u062d\u0628\u0648\u0628\u0627\u062a (\u0646\u062e\u0648\u062f\u060c \u0644\u0648\u0628\u06cc\u0627\u060c\u00a0<strong><a class=\"rl\" title=\"\u062e\u0648\u0627\u0635 \u0639\u062f\u0633\" href=\"https:\/\/namnak.com\/%D8%B9%D8%AF%D8%B3.p54579\" target=\"_blank\" rel=\"noopener noreferrer\">\u0639\u062f\u0633<\/a><\/strong>\u00a0\u0648 &#8230;) \u060c \u0645\u06cc\u0648\u0647 \u0647\u0627\u06cc \u062e\u0634\u06a9 (\u0627\u0646\u062c\u06cc\u0631 \u062e\u0634\u06a9\u060c\u062e\u0631\u0645\u0627\u060c\u00a0<strong><a class=\"rl\" title=\"\u062e\u0648\u0627\u0635 \u0632\u0631\u062f\u0622\u0644\u0648\" href=\"https:\/\/namnak.com\/%D8%AE%D9%88%D8%A7%D8%B5-%D9%85%D8%B6%D8%B1%D8%A7%D8%AA-%D8%B2%D8%B1%D8%AF%D8%A2%D9%84%D9%88.p15530\" target=\"_blank\" rel=\"noopener noreferrer\">\u0632\u0631\u062f\u0622\u0644\u0648<\/a><\/strong>\u00a0\u0648 &#8230; )\u0645\u0635\u0631\u0641 \u06a9\u0646\u0646\u062f.<\/p>\n<p>\u0648\u062c\u0648\u062f \u067e\u062a\u0627\u0633\u06cc\u0645 \u0633\u0628\u0628 \u0645\u06cc \u0634\u0648\u062f \u0627\u0633\u067e\u0631\u0645 \u0645\u0631\u062f\u0627\u0646 \u0632\u0645\u0627\u0646 \u0632\u06cc\u0627\u062f\u06cc \u062f\u0631\u0631\u062d\u0645 \u062e\u0627\u0646\u0645 \u0647\u0627 \u0628\u0627\u0642\u06cc \u0628\u0645\u0627\u0646\u062f \u0648 \u0628\u0647 \u0633\u0645\u062a \u062a\u062e\u0645\u06a9 \u062d\u0631\u06a9\u062a \u06a9\u0646\u062f \u062a\u0627 \u0644\u0642\u0627\u062d \u062f\u0631\u0631\u062d\u0645 \u062e\u0627\u0646\u0645 \u0628\u0627 \u0645\u0648\u0641\u0642\u06cc\u062a \u0627\u0646\u062c\u0627\u0645 \u06af\u06cc\u0631\u062f. \u0642\u0627\u0631\u0686 \u0648\u00a0<strong><a class=\"rl\" title=\"\u062e\u0648\u0627\u0635 \u0645\u0648\u0632\" href=\"https:\/\/namnak.com\/%D8%AE%D9%88%D8%A7%D8%B5-%D9%85%D9%88%D8%B2.p11194\" target=\"_blank\" rel=\"noopener noreferrer\">\u0645\u0648\u0632<\/a><\/strong>\u00a0\u060c \u0645\u0627\u0631\u0686\u0648\u0628\u0647\u060c\u00a0<strong><a class=\"rl\" title=\"\u062e\u0648\u0627\u0635 \u0633\u06cc\u0628\" href=\"https:\/\/namnak.com\/%D8%AE%D9%88%D8%A7%D8%B5-%D8%A8%DB%8C-%D9%86%D8%B8%DB%8C%D8%B1-%D8%B3%DB%8C%D8%A8.p5124\" target=\"_blank\" rel=\"noopener noreferrer\">\u0633\u06cc\u0628<\/a><\/strong>\u00a0\u0632\u0645\u06cc\u0646\u06cc\u060c \u0633\u06cc\u0628\u060c\u00a0<strong><a class=\"rl\" title=\"\u062e\u0648\u0627\u0635 \u0628\u0627\u062f\u0627\u0645\" href=\"https:\/\/namnak.com\/%D8%AE%D9%88%D8%A7%D8%B5-%D9%85%D9%81%DB%8C%D8%AF-%D8%A8%D8%A7%D8%AF%D8%A7%D9%85.p23927\" target=\"_blank\" rel=\"noopener noreferrer\">\u0628\u0627\u062f\u0627\u0645<\/a><\/strong>\u00a0\u0646\u06cc\u0632 \u0633\u0631\u0634\u0627\u0631 \u0627\u0632 \u067e\u062a\u0627\u0633\u06cc\u0645 \u0647\u0633\u062a\u0646\u062f\u0648 \u0645\u0635\u0631\u0641 \u0622\u0646 \u0647\u0627 \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<p><strong>\u0645\u0635\u0631\u0641 \u0645\u0631\u06a9\u0628\u0627\u062a<\/strong><\/p>\n<p>\u0645\u0631\u06a9\u0628\u0627\u062a \u0645\u0627\u0646\u0646\u062f\u00a0<strong><a class=\"rl\" title=\"\u062e\u0648\u0627\u0635 \u0644\u06cc\u0645\u0648 \u062a\u0631\u0634\" href=\"https:\/\/namnak.com\/%D8%AE%D9%88%D8%A7%D8%B5-%D8%A8%DB%8C-%D9%86%D8%B8%DB%8C%D8%B1-%D9%84%DB%8C%D9%85%D9%88%D8%AA%D8%B1%D8%B4.p14763\" target=\"_blank\" rel=\"noopener noreferrer\">\u0644\u06cc\u0645\u0648 \u062a\u0631\u0634<\/a><\/strong>\u060c\u00a0<strong><a class=\"rl\" title=\"\u062e\u0648\u0627\u0635 \u067e\u0631\u062a\u0642\u0627\u0644\" href=\"https:\/\/namnak.com\/%D8%AE%D9%88%D8%A7%D8%B5-%D9%BE%D8%B1%D8%AA%D9%82%D8%A7%D9%84.p314\" target=\"_blank\" rel=\"noopener noreferrer\">\u067e\u0631\u062a\u0642\u0627\u0644<\/a><\/strong>\u060c \u0646\u0627\u0631\u0646\u06af\u06cc\u060c\u00a0<strong><a class=\"rl\" title=\"\u062e\u0648\u0627\u0635 \u06af\u0631\u06cc\u067e \u0641\u0631\u0648\u062a\" href=\"https:\/\/namnak.com\/%D8%AE%D9%88%D8%A7%D8%B5-%DA%AF%D8%B1%DB%8C%D9%BE-%D9%81%D8%B1%D9%88%D8%AA.p39163\" target=\"_blank\" rel=\"noopener noreferrer\">\u06af\u0631\u06cc\u067e \u0641\u0631\u0648\u062a<\/a><\/strong>\u00a0\u0648&#8230; \u062d\u0627\u0648\u06cc\u00a0<strong><a class=\"rl\" title=\"\u062e\u0648\u0627\u0635 \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 c\" href=\"https:\/\/namnak.com\/%D8%AE%D9%88%D8%A7%D8%B5-%D9%85%D8%B9%D8%AC%D8%B2%D9%87-%D8%A2%D8%B3%D8%A7%DB%8C-%D9%88%DB%8C%D8%AA%D8%A7%D9%85%DB%8C%D9%86-c-.p51007\" target=\"_blank\" rel=\"noopener noreferrer\">\u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 C<\/a><\/strong>\u00a0\u0647\u0633\u062a\u0646\u062f \u0648 \u062f\u0631 \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0628\u062f\u0646 \u0648 \u0633\u0644\u0627\u0645\u062a \u062c\u0633\u0645 \u0648 \u0627\u06cc\u062c\u0627\u062f \u0645\u062d\u06cc\u0637 \u0642\u0644\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u0628\u062f\u0646 \u0646\u0642\u0634 \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0631\u0646\u062f . \u0645\u062d\u06cc\u0637 \u0642\u0644\u06cc\u0627\u06cc\u06cc\u060c \u0628\u0631\u0627\u06cc \u0631\u0634\u062f \u0648 \u0628\u0642\u0627\u06cc \u0627\u0633\u067e\u0631\u0645 \u0647\u0627\u06cc \u0645\u0631\u062f\u0627\u0646\u0647 \u0645\u062b\u0644 \u06a9\u0631\u0648\u0645\u0648\u0632\u0648\u0645 Y \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a.<\/p>\n<h4 class=\"tcr\">\u0631\u0698\u06cc\u0645 \u063a\u0630\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u067e\u0633\u0631\u062f\u0627\u0631 \u0634\u062f\u0646<\/h4>\n<h3>\u0632\u0645\u0627\u0646 \u0634\u0631\u0648\u0639 \u0631\u0698\u06cc\u0645 \u063a\u0630\u0627\u06cc\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u067e\u0633\u0631\u062f\u0627\u0631 \u0634\u062f\u0646<\/h3>\n<p>\u0628\u0631\u0627\u06cc \u067e\u0633\u0631 \u062f\u0627\u0631 \u0634\u062f\u0646 \u062a\u0642\u0631\u06cc\u0628\u0627 \u062f\u0648 \u06cc\u0627 \u0633\u0647 \u0645\u0627\u0647 \u0642\u0628\u0644 \u0627\u0632 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0628\u0627\u06cc\u062f \u0631\u0698\u06cc\u0645 \u063a\u0630\u0627\u06cc\u06cc \u062e\u0648\u062f \u0631\u0627 \u0634\u0631\u0648\u0639 \u06a9\u0646\u06cc\u062f. \u062a\u063a\u0630\u06cc\u0647 \u062f\u0631\u00a0<em>\u062a\u0639\u06cc\u06cc\u0646 \u062c\u0646\u0633\u06cc\u062a\u00a0\u062c\u0646\u06cc\u0646<\/em>\u00a0\u062d\u062f\u0648\u062f 70 \u062a\u0627 80 \u062f\u0631\u0635\u062f \u0646\u0642\u0634 \u062f\u0627\u0631\u062f \u0648 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0633\u0628\u0628 \u062a\u063a\u06cc\u06cc\u0631 \u06cc\u0648\u0646 \u0647\u0627 \u0648 \u062a\u063a\u06cc\u06cc\u0631\u062a\u062e\u0645\u06a9 \u0647\u0627 \u0634\u0648\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u0641\u0627\u06a9\u062a\u0648\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0631 \u0631\u0648\u06cc\u00a0\u062a\u0639\u06cc\u06cc\u0646 \u062c\u0646\u0633\u06cc\u062a\u00a0\u0627\u062b\u0631 \u06af\u0630\u0627\u0631 \u0627\u0633\u062a . \u0627\u06af\u0631 \u0634\u0645\u0627 \u0645\u0627\u06cc\u0644\u06cc\u062f \u067e\u0633\u0631 \u062f\u0627\u0631 \u0634\u0648\u06cc\u062f \u060c \u0631\u0648\u0634 \u0647\u0627\u06cc \u062e\u0627\u0635 \u0648 \u0645\u0637\u0645\u0626\u0646\u06cc \u0628\u0631\u0627\u06cc\u00a0\u067e\u0633\u0631 \u062f\u0627\u0631 \u0634\u062f\u0646\u00a0\u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0628\u0631\u0627\u06cc\u00a0\u067e\u0633\u0631 \u0634\u062f\u0646 \u062c\u0646\u06cc\u0646\u00a0\u0646\u0648\u0639 \u062a\u063a\u0630\u06cc\u0647 \u0634\u0645\u0627 \u0648 \u0647\u0645\u0633\u0631\u062a\u0627\u0646 \u0648 \u0627\u0642\u062f\u0627\u0645 \u0628\u0647\u00a0\u0628\u0627\u0631\u062f\u0627\u0631\u06cc\u00a0\u062f\u0631 \u0641\u0635\u0644 \u0648 \u0634\u0631\u0627\u06cc\u0637 \u062e\u0627\u0635 \u0628\u06cc \u062a\u0627\u062b\u06cc\u0631 \u0646\u06cc\u0633\u062a . \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0631\u0627\u0647\u06cc \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u0627\u0646\u0633\u00a0\u067e\u0633\u0631\u062f\u0627\u0631 \u0634\u062f\u0646\u00a0\u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u06cc\u0646 \u0628\u062e\u0634 \u0627\u0632\u00a0\u0628\u0627\u0631\u062f\u0627\u0631\u06cc\u00a0\u0646\u0645\u0646\u0627\u06a9\u00a0\u0631\u0648\u0634 \u0647\u0627\u06cc [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7844],"tags":[],"class_list":["post-90242","post","type-post","status-publish","format-standard","hentry","category-7844"],"views":433,"_links":{"self":[{"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/posts\/90242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/comments?post=90242"}],"version-history":[{"count":0,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/posts\/90242\/revisions"}],"wp:attachment":[{"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/media?parent=90242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/categories?post=90242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/tags?post=90242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}