{"id":94263,"date":"2021-02-23T23:50:55","date_gmt":"2021-02-23T20:20:55","guid":{"rendered":"https:\/\/tarikhema.org\/info\/?p=94263"},"modified":"2021-02-23T20:26:01","modified_gmt":"2021-02-23T16:56:01","slug":"%d9%86%d8%ad%d9%88%d9%87-%d8%b5%d8%ad%db%8c%d8%ad-%d8%b0%d8%a8%d8%ad-%d9%85%d8%b1%d8%ba-%da%86%da%af%d9%88%d9%86%d9%87-%d8%a7%d8%b3%d8%aa%d8%9f","status":"publish","type":"post","link":"https:\/\/tarikhema.org\/info\/94263\/%d9%86%d8%ad%d9%88%d9%87-%d8%b5%d8%ad%db%8c%d8%ad-%d8%b0%d8%a8%d8%ad-%d9%85%d8%b1%d8%ba-%da%86%da%af%d9%88%d9%86%d9%87-%d8%a7%d8%b3%d8%aa%d8%9f\/","title":{"rendered":"\u0646\u062d\u0648\u0647 \u0635\u062d\u06cc\u062d \u0630\u0628\u062d \u0645\u0631\u063a \u0686\u06af\u0648\u0646\u0647 \u0627\u0633\u062a\u061f"},"content":{"rendered":"<div class=\"bs-shortcode-alert alert alert-info\">\u0634\u06cc\u0648\u0647 \u0635\u062d\u06cc\u062d \u0630\u0628\u062d \u0627\u0633\u0644\u0627\u0645\u06cc<br \/>\n\u062f\u0631 \u0641\u0642\u0647 \u0627\u0633\u0644\u0627\u0645\u06cc \u0628\u0631\u0627\u06cc \u0630\u0628\u062d \u062d\u06cc\u0648\u0627\u0646\u060c \u0634\u0631\u0627\u06cc\u0637\u060c \u0631\u0648\u0634 \u0648 \u0622\u062f\u0627\u0628\u06cc \u0628\u06cc\u0627\u0646 \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0634\u0631\u062d \u0622\u0646 \u0686\u0646\u06cc\u0646 \u0627\u0633\u062a:<br \/>\n\u0627\u0644\u0641. \u0634\u0631\u0627\u06cc\u0637 \u0630\u0628\u062d \u062d\u06cc\u0648\u0627\u0646<br \/>\n\u06f1. \u06a9\u0633\u0649 \u06a9\u0647 \u0633\u0631 \u062d\u06cc\u0648\u0627\u0646 \u0631\u0627 \u0645\u06cc\u200c\u0628\u064f\u0631\u062f \u0645\u0633\u0644\u0645\u0627\u0646 \u0628\u0648\u062f\u0647 \u0648 \u0627\u0638\u0647\u0627\u0631 \u062f\u0634\u0645\u0646\u0649 \u0628\u0627 \u0623\u0647\u0644 \u0628\u06cc\u062a \u067e\u06cc\u0627\u0645\u0628\u0631 (\u0635) \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<br \/>\n\u06f2. \u0633\u0631 \u062d\u06cc\u0648\u0627\u0646 \u0631\u0627 \u0628\u0627 \u0686\u06cc\u0632\u0649 \u0628\u0628\u064f\u0631\u062f \u06a9\u0647 \u0627\u0632 \u0622\u0647\u0646 \u0628\u0627\u0634\u062f\u060c \u0648\u0644\u0649 \u0686\u0646\u0627\u0646\u0686\u0647 \u0622\u0647\u0646 \u067e\u06cc\u062f\u0627 \u0646\u0634\u062f \u0648 \u0646\u0627\u0686\u0627\u0631 \u0628\u0647 \u0630\u0628\u062d \u0634\u062f (\u0637\u0648\u0631\u06cc \u06a9\u0647 \u0627\u06af\u0631 \u062d\u06cc\u0648\u0627\u0646 \u0630\u0628\u062d \u0646\u0634\u0648\u062f\u060c \u062a\u0644\u0641 \u0634\u0648\u062f)\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0633\u0631 \u0622\u0646\u200c\u0631\u0627 \u0628\u0627 \u0686\u06cc\u0632 \u062a\u06cc\u0632\u0649 \u0628\u0631\u06cc\u062f \u06a9\u0647 \u0686\u0647\u0627\u0631 \u0631\u06af \u0622\u0646\u200c\u0631\u0627 \u062c\u062f\u0627 \u06a9\u0646\u062f\u061b \u0645\u0627\u0646\u0646\u062f \u0634\u06cc\u0634\u0647 \u0648 \u0633\u0646\u06af \u062a\u06cc\u0632.<br \/>\n\u06f3. \u062f\u0631 \u0645\u0648\u0642\u0639 \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646\u060c \u062c\u0644\u0648\u06cc \u0628\u062f\u0646 \u062d\u06cc\u0648\u0627\u0646 \u0631\u0648\u06cc \u0628\u0647 \u0642\u0628\u0644\u0647 \u0628\u0627\u0634\u062f. \u067e\u0633 \u0627\u06af\u0631 \u0639\u0645\u062f\u0627\u064b \u062d\u06cc\u0648\u0627\u0646 \u0631\u0627 \u0631\u0648 \u0628\u0647 \u0642\u0628\u0644\u0647 \u0646\u06a9\u0646\u062f \u062d\u06cc\u0648\u0627\u0646 \u062d\u0631\u0627\u0645 \u0645\u0649\u200c\u0634\u0648\u062f\u060c \u0648\u0644\u0649 \u0627\u06af\u0631 \u0641\u0631\u0627\u0645\u0648\u0634 \u06a9\u0646\u062f \u06cc\u0627 \u0645\u0633\u0626\u0644\u0647 \u0631\u0627 \u0646\u062f\u0627\u0646\u062f \u06cc\u0627 \u0642\u0628\u0644\u0647 \u0631\u0627 \u0627\u0634\u062a\u0628\u0627\u0647 \u06a9\u0646\u062f \u06cc\u0627 \u0646\u062f\u0627\u0646\u062f \u0642\u0628\u0644\u0647 \u06a9\u062f\u0627\u0645 \u0637\u0631\u0641 \u0627\u0633\u062a \u0648 \u06cc\u0627 \u0646\u062a\u0648\u0627\u0646\u062f \u062d\u06cc\u0648\u0627\u0646 \u0631\u0627 \u0631\u0648 \u0628\u0647 \u0642\u0628\u0644\u0647 \u06a9\u0646\u062f\u060c \u0627\u0634\u06a9\u0627\u0644 \u0646\u062f\u0627\u0631\u062f \u0648 \u062d\u06cc\u0648\u0627\u0646 \u062d\u0631\u0627\u0645 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f.<br \/>\n\u06f4. \u0648\u0642\u062a\u0649 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u0633\u0631 \u062d\u06cc\u0648\u0627\u0646 \u0631\u0627 \u0628\u0628\u0631\u062f\u060c \u06a9\u0627\u0631\u062f \u0628\u0631 \u06af\u0644\u0648\u06cc\u0634 \u0628\u0647 \u0646\u06cc\u0651\u062a \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u0628\u06af\u0630\u0627\u0631\u062f \u0648 \u0646\u0627\u0645 \u062e\u062f\u0627 \u0631\u0627 \u0628\u0628\u0631\u062f \u0648 \u0647\u0645\u06cc\u0646 \u0642\u062f\u0631 \u06a9\u0647 \u0628\u06af\u0648\u06cc\u062f \u00ab\u0628\u0633\u0645 \u0627\u0644\u0644\u0651\u0670\u0647\u00bb \u06a9\u0627\u0641\u0649 \u0627\u0633\u062a\u061b \u0648 \u0627\u06af\u0631 \u0628\u062f\u0648\u0646 \u0642\u0635\u062f \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u0646\u0627\u0645 \u062e\u062f\u0627 \u0631\u0627 \u0628\u0628\u0631\u062f\u060c \u0622\u0646 \u062d\u06cc\u0648\u0627\u0646 \u067e\u0627\u06a9 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u06af\u0648\u0634\u062a \u0622\u0646 \u0647\u0645 \u062d\u0631\u0627\u0645 \u0627\u0633\u062a\u060c \u0648\u0644\u0649 \u0627\u06af\u0631 \u0627\u0632 \u0631\u0648\u0649 \u0641\u0631\u0627\u0645\u0648\u0634\u0649 \u0646\u0627\u0645 \u062e\u062f\u0627 \u0631\u0627 \u0646\u0628\u0631\u062f \u0627\u0634\u06a9\u0627\u0644 \u0646\u062f\u0627\u0631\u062f \u0648 \u062d\u06cc\u0648\u0627\u0646 \u062d\u0631\u0627\u0645 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f.<br \/>\n\u06f5. \u062d\u06cc\u0648\u0627\u0646 \u0628\u0639\u062f \u0627\u0632 \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u062d\u0631\u06a9\u062a\u0649 \u06a9\u0646\u062f. \u0627\u06af\u0631 \u0686\u0647 \u0645\u062b\u0644\u0627\u064b \u0686\u0634\u0645 \u06cc\u0627 \u062f\u0645 \u062e\u0648\u062f \u0631\u0627 \u062d\u0631\u06a9\u062a \u062f\u0647\u062f\u060c \u06cc\u0627 \u067e\u0627\u0649 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0632\u0645\u06cc\u0646 \u0632\u0646\u062f \u06a9\u0647 \u0645\u0639\u0644\u0648\u0645 \u0634\u0648\u062f \u0632\u0646\u062f\u0647 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a.<br \/>\n\u06f6. \u0628\u0639\u062f \u0627\u0632 \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u06c0 \u0645\u0639\u0645\u0648\u0644 \u062e\u0648\u0646 \u0627\u0632 \u0628\u062f\u0646 \u062d\u06cc\u0648\u0627\u0646 \u0628\u06cc\u0631\u0648\u0646 \u0622\u06cc\u062f<br \/>\n\u0628. \u0686\u06af\u0648\u0646\u06af\u06cc \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u062d\u06cc\u0648\u0627\u0646<br \/>\n\u062f\u0633\u062a\u0648\u0631 \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u062d\u06cc\u0648\u0627\u0646 \u0622\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062d\u0644\u0642\u0648\u0645 (\u0645\u062c\u0631\u0627\u0649 \u062a\u0646\u0641\u0633) \u0648 \u0645\u0650\u0631\u0649 (\u0645\u062c\u0631\u0627\u0649 \u063a\u0630\u0627) \u0648 \u062f\u0648 \u0634\u0627\u0647\u0631\u06af \u0631\u0627 \u06a9\u0647 \u062f\u0631 \u062f\u0648 \u0637\u0631\u0641 \u062d\u0644\u0642\u0648\u0645 \u0627\u0633\u062a (\u0648 \u0628\u0647 \u0627\u06cc\u0646 \u0686\u0647\u0627\u0631 \u062a\u0627 \u00ab\u0623\u0648\u062f\u0627\u062c \u0623\u0631\u0628\u0639\u0647\u00bb \u06af\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f)\u060c \u0627\u0632 \u067e\u0627\u06cc\u06cc\u0646 \u0628\u0631\u0622\u0645\u062f\u06af\u0649 \u0632\u06cc\u0631 \u06af\u0644\u0648\u060c \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0628\u064f\u0631\u0646\u062f\u060c \u0648 \u0627\u06af\u0631 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0634\u06a9\u0627\u0641\u0646\u062f \u06a9\u0627\u0641\u0649 \u0646\u06cc\u0633\u062a\u061b \u0648 \u062f\u0631 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647\u060c \u0628\u0627\u06cc\u062f \u0628\u0647 \u062f\u0648 \u0646\u06a9\u062a\u0647 \u062a\u0648\u062c\u0647 \u0634\u0648\u062f:<br \/>\n\u06f1. \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u0628\u0631\u06cc\u062f\u0646 \u0631\u06af\u200c\u0647\u0627 \u0648 \u0645\u062c\u0627\u0631\u06cc\u060c \u067e\u0634\u062a \u0633\u0631 \u0647\u0645 \u0628\u0627\u0634\u062f. \u067e\u0633 \u0627\u06af\u0631 \u0628\u0639\u0636\u0649 \u0627\u0632 \u0631\u06af\u200c\u0647\u0627 \u0631\u0627 \u0628\u0628\u064f\u0631\u062f \u0648 \u0635\u0628\u0631 \u06a9\u0646\u062f \u062a\u0627 \u062d\u06cc\u0648\u0627\u0646 \u0628\u0645\u06cc\u0631\u062f\u060c \u0633\u067e\u0633 \u0628\u0642\u06cc\u0651\u0647 \u0631\u0627 \u0628\u0628\u0631\u062f \u0641\u0627\u06cc\u062f\u0647 \u0646\u062f\u0627\u0634\u062a\u0647 \u0648 \u062d\u06cc\u0648\u0627\u0646 \u062d\u0631\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0627\u06af\u0631 \u062f\u0631 \u0627\u06cc\u0646 \u0641\u0627\u0635\u0644\u0647 \u062d\u06cc\u0648\u0627\u0646 \u0647\u0645 \u0646\u0645\u06cc\u0631\u062f\u060c \u0648\u0644\u0649 \u0628\u0647 \u0637\u0648\u0631 \u0645\u0639\u0645\u0648\u0644 \u0686\u0647\u0627\u0631 \u0631\u06af \u0631\u0627 \u067e\u0634\u062a \u0633\u0631 \u0647\u0645 \u0646\u0628\u0631\u0646\u062f \u0627\u0634\u06a9\u0627\u0644 \u062f\u0627\u0631\u062f \u0648 \u062d\u06cc\u0648\u0627\u0646 \u062d\u0644\u0627\u0644 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f.<br \/>\n\u06f2. \u067e\u06cc\u0634 \u0627\u0632 \u0628\u06cc\u0631\u0648\u0646 \u0622\u0645\u062f\u0646 \u0631\u0648\u062d\u060c \u062c\u062f\u0627 \u06a9\u0631\u062f\u0646 \u0633\u0631 \u062d\u06cc\u0648\u0627\u0646 \u0627\u0632 \u0628\u062f\u0646 \u062d\u0631\u0627\u0645 \u0627\u0633\u062a\u060c \u0648\u0644\u0649 \u0628\u0627 \u0627\u06cc\u0646 \u0639\u0645\u0644 \u062d\u06cc\u0648\u0627\u0646 \u062d\u0631\u0627\u0645 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u062d\u062a\u06cc\u0627\u0637 \u0622\u0646 \u0627\u0633\u062a \u06a9\u0647 \u067e\u06cc\u0634 \u0627\u0632 \u0628\u06cc\u0631\u0648\u0646 \u0622\u0645\u062f\u0646 \u0631\u0648\u062d\u060c \u067e\u0648\u0633\u062a \u062d\u06cc\u0648\u0627\u0646 \u0631\u0627 \u0646\u06a9\u064e\u0646\u0646\u062f\u060c \u0648 \u0645\u063a\u0632 \u062d\u0631\u0627\u0645 \u0631\u0627 \u06a9\u0647 \u062f\u0631 \u062a\u06cc\u0631\u06c0 \u067e\u0634\u062a \u0627\u0633\u062a\u060c \u0646\u0628\u064f\u0631\u0651\u0646\u062f.<br \/>\n\u06f3. \u0627\u06af\u0631 \u0628\u062e\u0648\u0627\u0647\u0646\u062f \u0634\u062a\u0631 \u0631\u0627 \u0628\u06a9\u0634\u0646\u062f \u06a9\u0647 \u0628\u0639\u062f \u0627\u0632 \u062c\u0627\u0646 \u062f\u0627\u062f\u0646 \u067e\u0627\u06a9 \u0648 \u062d\u0644\u0627\u0644 \u0628\u0627\u0634\u062f \u0628\u0627\u06cc\u062f \u0628\u0627 \u0634\u0631\u0627\u06cc\u0637\u06cc \u06a9\u0647 \u0628\u0631\u0627\u0649 \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u062d\u06cc\u0648\u0627\u0646 \u06af\u0641\u062a\u0647 \u0634\u062f\u060c \u0686\u0627\u0642\u0648 \u06cc\u0627 \u0686\u06cc\u0632 \u062f\u06cc\u06af\u0631\u0649 \u0631\u0627 \u06a9\u0647 \u0627\u0632 \u0622\u0647\u0646 \u0648 \u0628\u0631\u0646\u062f\u0647 \u0628\u0627\u0634\u062f\u060c \u062f\u0631 \u06af\u0648\u062f\u0649 \u0628\u06cc\u0646 \u06af\u0631\u062f\u0646 \u0648 \u0633\u06cc\u0646\u0647 \u0627\u0634 \u0641\u0631\u0648 \u06a9\u0646\u0646\u062f (\u06a9\u0647 \u0627\u06cc\u0646 \u0639\u0645\u0644 \u0631\u0627 \u00ab\u0646\u062d\u0631\u00bb \u0645\u06cc\u200c\u06af\u0648\u06cc\u0646\u062f) \u0648 \u0628\u0647\u062a\u0631 \u0622\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0634\u062a\u0631 \u062f\u0631 \u0627\u06cc\u0646 \u0647\u0646\u06af\u0627\u0645 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0628\u0627\u0634\u062f.<br \/>\n\u062c. \u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u0645\u0648\u0642\u0639 \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u062d\u06cc\u0648\u0627\u0646\u060c \u0631\u0639\u0627\u06cc\u062a \u0622\u0646\u200c\u0647\u0627 \u0645\u0633\u062a\u062d\u0628\u0651 \u0627\u0633\u062a\u200c:<br \/>\n\u06f1. \u0645\u0648\u0642\u0639 \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646\u0650 \u06af\u0648\u0633\u0641\u0646\u062f \u062f\u0648 \u062f\u0633\u062a \u0648 \u06cc\u06a9 \u067e\u0627\u0649 \u0622\u0646\u200c\u0631\u0627 \u0628\u0628\u0646\u062f\u0646\u062f \u0648 \u067e\u0627\u0649 \u062f\u06cc\u06af\u0631\u0634 \u0631\u0627 \u0628\u0627\u0632 \u0628\u06af\u0630\u0627\u0631\u0646\u062f \u0648 \u0645\u0648\u0642\u0639 \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u06af\u0627\u0648 \u0686\u0647\u0627\u0631 \u062f\u0633\u062a \u0648 \u067e\u0627\u06cc\u0634 \u0631\u0627 \u0628\u0628\u0646\u062f\u0646\u062f \u0648 \u062f\u064f\u0645 \u0622\u0646\u200c\u0631\u0627 \u0628\u0627\u0632 \u0628\u06af\u0630\u0627\u0631\u0646\u062f \u0648 \u0645\u0648\u0642\u0639 \u06a9\u0634\u062a\u0646 \u0634\u062a\u0631 \u062f\u0648 \u062f\u0633\u062a \u0622\u0646\u200c\u0631\u0627 \u0627\u0632 \u067e\u0627\u06cc\u06cc\u0646 \u062a\u0627 \u0632\u0627\u0646\u0648 \u06cc\u0627 \u062a\u0627 \u0632\u06cc\u0631 \u0628\u063a\u0644 \u0628\u0647 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0628\u0628\u0646\u062f\u0646\u062f \u0648 \u067e\u0627\u0647\u0627\u06cc\u0634 \u0631\u0627 \u0628\u0627\u0632 \u0628\u06af\u0630\u0627\u0631\u0646\u062f \u0648 \u0645\u0633\u062a\u062d\u0628\u0651 \u0627\u0633\u062a \u0645\u0631\u063a \u0631\u0627 \u0628\u0639\u062f \u0627\u0632 \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u0631\u0647\u0627 \u06a9\u0646\u0646\u062f \u062a\u0627 \u067e\u0631 \u0648 \u0628\u0627\u0644 \u0628\u0632\u0646\u062f.<br \/>\n\u06f2. \u06a9\u0633\u0649 \u06a9\u0647 \u062d\u06cc\u0648\u0627\u0646 \u0631\u0627 \u0645\u06cc\u200c\u06a9\u0634\u062f\u060c \u0631\u0648 \u0628\u0647 \u0642\u0628\u0644\u0647 \u0628\u0627\u0634\u062f.<br \/>\n\u06f3. \u067e\u06cc\u0634 \u0627\u0632 \u06a9\u0634\u062a\u0646 \u062d\u06cc\u0648\u0627\u0646\u060c \u0622\u0628 \u062c\u0644\u0648\u0649 \u0622\u0646 \u0628\u06af\u0630\u0627\u0631\u0646\u062f.<br \/>\n\u06f4. \u06a9\u0627\u0631\u0649 \u06a9\u0646\u0646\u062f \u06a9\u0647 \u062d\u06cc\u0648\u0627\u0646 \u06a9\u0645\u062a\u0631 \u0627\u0630\u06cc\u062a \u0634\u0648\u062f\u060c \u0645\u062b\u0644\u0627\u064b \u06a9\u0627\u0631\u062f \u0631\u0627 \u062e\u0648\u0628 \u062a\u06cc\u0632 \u06a9\u0646\u0646\u062f \u0648 \u0628\u0627 \u0639\u062c\u0644\u0647 \u0633\u0631 \u062d\u06cc\u0648\u0627\u0646 \u0631\u0627 \u0628\u0628\u0631\u0646\u062f.<\/div>\n<h4>\u0645\u0634\u0627\u0628\u0647<\/h4><ul><li>https:\/\/tarikhema org\/info\/94263\/\u0646\u062d\u0648\u0647-\u0635\u062d\u06cc\u062d-\u0630\u0628\u062d-\u0645\u0631\u063a-\u0686\u06af\u0648\u0646\u0647-\u0627\u0633\u062a\u061f\/<\/li><li>https:\/\/tarikhema org\/info\/94263\/\u0646\u062d\u0648\u0647-\u0635\u062d\u06cc\u062d-\u0630\u0628\u062d-\u0645\u0631\u063a-\u0686\u06af\u0648\u0646\u0647-\u0627\u0633\u062a\u061f\/#:~:text=\u062f\u0633\u062a\u0648\u0631 \u0633\u0631 \u0628\u0631\u06cc\u062f\u0646 \u062d\u06cc\u0648\u0627\u0646 \u0622\u0646 \u06f1<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>\u0634\u06cc\u0648\u0647 \u0635\u062d\u06cc\u062d \u0630\u0628\u062d \u0627\u0633\u0644\u0627\u0645\u06cc \u062f\u0631 \u0641\u0642\u0647 \u0627\u0633\u0644\u0627\u0645\u06cc \u0628\u0631\u0627\u06cc \u0630\u0628\u062d \u062d\u06cc\u0648\u0627\u0646\u060c \u0634\u0631\u0627\u06cc\u0637\u060c \u0631\u0648\u0634 \u0648 \u0622\u062f\u0627\u0628\u06cc \u0628\u06cc\u0627\u0646 \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0634\u0631\u062d \u0622\u0646 \u0686\u0646\u06cc\u0646 \u0627\u0633\u062a: \u0627\u0644\u0641. \u0634\u0631\u0627\u06cc\u0637 \u0630\u0628\u062d \u062d\u06cc\u0648\u0627\u0646 \u06f1. \u06a9\u0633\u0649 \u06a9\u0647 \u0633\u0631 \u062d\u06cc\u0648\u0627\u0646 \u0631\u0627 \u0645\u06cc\u200c\u0628\u064f\u0631\u062f \u0645\u0633\u0644\u0645\u0627\u0646 \u0628\u0648\u062f\u0647 \u0648 \u0627\u0638\u0647\u0627\u0631 \u062f\u0634\u0645\u0646\u0649 \u0628\u0627 \u0623\u0647\u0644 \u0628\u06cc\u062a \u067e\u06cc\u0627\u0645\u0628\u0631 (\u0635) \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u06f2. \u0633\u0631 \u062d\u06cc\u0648\u0627\u0646 \u0631\u0627 \u0628\u0627 \u0686\u06cc\u0632\u0649 \u0628\u0628\u064f\u0631\u062f \u06a9\u0647 \u0627\u0632 \u0622\u0647\u0646 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":94264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7844,15],"tags":[27454],"class_list":["post-94263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-7844","category-heyvanat","tag-27454"],"views":30593,"_links":{"self":[{"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/posts\/94263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/comments?post=94263"}],"version-history":[{"count":0,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/posts\/94263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/media\/94264"}],"wp:attachment":[{"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/media?parent=94263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/categories?post=94263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tarikhema.org\/info\/wp-json\/wp\/v2\/tags?post=94263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}