{"id":1721,"count":1,"description":"","link":"https:\/\/tarikhema.org\/pishvaz\/tag\/%d9%85%d8%ad%d9%85%d8%af-%d8%a2%d8%b1%db%8c%d8%a7%d9%86%db%8c\/","name":"\u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc","slug":"%d9%85%d8%ad%d9%85%d8%af-%d8%a2%d8%b1%db%8c%d8%a7%d9%86%db%8c","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u062a\u0645\u0627\u0645 \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc ~ \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0645\u0648\u0628\u0627\u06cc\u0644<\/title>\n<meta name=\"description\" content=\"\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062a\u0645\u0627\u0645 \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u0633\u06cc\u0645 \u06a9\u0627\u0631\u062a \u0647\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646\u0633\u0644 \u060c \u0647\u0645\u0631\u0627\u0647 \u0627\u0648\u0644 \u0648 \u0631\u0627\u06cc\u062a\u0644 \u062f\u0631 \u0648\u0628\u0633\u0627\u06cc\u062a \u062a\u0627\u0631\u06cc\u062e \u0645\u0627 \u067e\u06cc\u0634\u0648\u0627\u0632\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tarikhema.org\/pishvaz\/tag\/\u0645\u062d\u0645\u062f-\u0622\u0631\u06cc\u0627\u0646\u06cc\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0628\u0627\u06cc\u06af\u0627\u0646\u06cc\u200c\u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc\" \/>\n<meta property=\"og:description\" content=\"\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062a\u0645\u0627\u0645 \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u0633\u06cc\u0645 \u06a9\u0627\u0631\u062a \u0647\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646\u0633\u0644 \u060c \u0647\u0645\u0631\u0627\u0647 \u0627\u0648\u0644 \u0648 \u0631\u0627\u06cc\u062a\u0644 \u062f\u0631 \u0648\u0628\u0633\u0627\u06cc\u062a \u062a\u0627\u0631\u06cc\u062e \u0645\u0627 \u067e\u06cc\u0634\u0648\u0627\u0632\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tarikhema.org\/pishvaz\/tag\/\u0645\u062d\u0645\u062f-\u0622\u0631\u06cc\u0627\u0646\u06cc\/\" \/>\n<meta property=\"og:site_name\" content=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0645\u0648\u0628\u0627\u06cc\u0644\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/tarikhema.org\\\/pishvaz\\\/tag\\\/%d9%85%d8%ad%d9%85%d8%af-%d8%a2%d8%b1%db%8c%d8%a7%d9%86%db%8c\\\/\",\"url\":\"https:\\\/\\\/tarikhema.org\\\/pishvaz\\\/tag\\\/%d9%85%d8%ad%d9%85%d8%af-%d8%a2%d8%b1%db%8c%d8%a7%d9%86%db%8c\\\/\",\"name\":\"\u062a\u0645\u0627\u0645 \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc ~ \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0645\u0648\u0628\u0627\u06cc\u0644\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tarikhema.org\\\/pishvaz\\\/#website\"},\"description\":\"\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062a\u0645\u0627\u0645 \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u0633\u06cc\u0645 \u06a9\u0627\u0631\u062a \u0647\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646\u0633\u0644 \u060c \u0647\u0645\u0631\u0627\u0647 \u0627\u0648\u0644 \u0648 \u0631\u0627\u06cc\u062a\u0644 \u062f\u0631 \u0648\u0628\u0633\u0627\u06cc\u062a \u062a\u0627\u0631\u06cc\u062e \u0645\u0627 \u067e\u06cc\u0634\u0648\u0627\u0632\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tarikhema.org\\\/pishvaz\\\/tag\\\/%d9%85%d8%ad%d9%85%d8%af-%d8%a2%d8%b1%db%8c%d8%a7%d9%86%db%8c\\\/#breadcrumb\"},\"inLanguage\":\"fa-IR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tarikhema.org\\\/pishvaz\\\/tag\\\/%d9%85%d8%ad%d9%85%d8%af-%d8%a2%d8%b1%db%8c%d8%a7%d9%86%db%8c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\\\/\\\/tarikhema.org\\\/pishvaz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tarikhema.org\\\/pishvaz\\\/#website\",\"url\":\"https:\\\/\\\/tarikhema.org\\\/pishvaz\\\/\",\"name\":\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0645\u0648\u0628\u0627\u06cc\u0644\",\"description\":\"\u062f\u0627\u0646\u0644\u0648\u062f \u0622\u0647\u0646\u06af \u067e\u06cc\u0634\u0648\u0627\u0632 \u0627\u06cc\u0631\u0627\u0646\u0633\u0644 \u0648 \u0647\u0645\u0631\u0627\u0647 \u0627\u0648\u0644 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e \u0645\u0627\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tarikhema.org\\\/pishvaz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u062a\u0645\u0627\u0645 \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc ~ \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0645\u0648\u0628\u0627\u06cc\u0644","description":"\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062a\u0645\u0627\u0645 \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u0633\u06cc\u0645 \u06a9\u0627\u0631\u062a \u0647\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646\u0633\u0644 \u060c \u0647\u0645\u0631\u0627\u0647 \u0627\u0648\u0644 \u0648 \u0631\u0627\u06cc\u062a\u0644 \u062f\u0631 \u0648\u0628\u0633\u0627\u06cc\u062a \u062a\u0627\u0631\u06cc\u062e \u0645\u0627 \u067e\u06cc\u0634\u0648\u0627\u0632","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tarikhema.org\/pishvaz\/tag\/\u0645\u062d\u0645\u062f-\u0622\u0631\u06cc\u0627\u0646\u06cc\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0628\u0627\u06cc\u06af\u0627\u0646\u06cc\u200c\u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc","og_description":"\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062a\u0645\u0627\u0645 \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u0633\u06cc\u0645 \u06a9\u0627\u0631\u062a \u0647\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646\u0633\u0644 \u060c \u0647\u0645\u0631\u0627\u0647 \u0627\u0648\u0644 \u0648 \u0631\u0627\u06cc\u062a\u0644 \u062f\u0631 \u0648\u0628\u0633\u0627\u06cc\u062a \u062a\u0627\u0631\u06cc\u062e \u0645\u0627 \u067e\u06cc\u0634\u0648\u0627\u0632","og_url":"https:\/\/tarikhema.org\/pishvaz\/tag\/\u0645\u062d\u0645\u062f-\u0622\u0631\u06cc\u0627\u0646\u06cc\/","og_site_name":"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0645\u0648\u0628\u0627\u06cc\u0644","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/tarikhema.org\/pishvaz\/tag\/%d9%85%d8%ad%d9%85%d8%af-%d8%a2%d8%b1%db%8c%d8%a7%d9%86%db%8c\/","url":"https:\/\/tarikhema.org\/pishvaz\/tag\/%d9%85%d8%ad%d9%85%d8%af-%d8%a2%d8%b1%db%8c%d8%a7%d9%86%db%8c\/","name":"\u062a\u0645\u0627\u0645 \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc ~ \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0645\u0648\u0628\u0627\u06cc\u0644","isPartOf":{"@id":"https:\/\/tarikhema.org\/pishvaz\/#website"},"description":"\u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062a\u0645\u0627\u0645 \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0647\u0627\u06cc \u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u0633\u06cc\u0645 \u06a9\u0627\u0631\u062a \u0647\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646\u0633\u0644 \u060c \u0647\u0645\u0631\u0627\u0647 \u0627\u0648\u0644 \u0648 \u0631\u0627\u06cc\u062a\u0644 \u062f\u0631 \u0648\u0628\u0633\u0627\u06cc\u062a \u062a\u0627\u0631\u06cc\u062e \u0645\u0627 \u067e\u06cc\u0634\u0648\u0627\u0632","breadcrumb":{"@id":"https:\/\/tarikhema.org\/pishvaz\/tag\/%d9%85%d8%ad%d9%85%d8%af-%d8%a2%d8%b1%db%8c%d8%a7%d9%86%db%8c\/#breadcrumb"},"inLanguage":"fa-IR"},{"@type":"BreadcrumbList","@id":"https:\/\/tarikhema.org\/pishvaz\/tag\/%d9%85%d8%ad%d9%85%d8%af-%d8%a2%d8%b1%db%8c%d8%a7%d9%86%db%8c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/tarikhema.org\/pishvaz\/"},{"@type":"ListItem","position":2,"name":"\u0645\u062d\u0645\u062f \u0622\u0631\u06cc\u0627\u0646\u06cc"}]},{"@type":"WebSite","@id":"https:\/\/tarikhema.org\/pishvaz\/#website","url":"https:\/\/tarikhema.org\/pishvaz\/","name":"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062f \u067e\u06cc\u0634\u0648\u0627\u0632 \u0645\u0648\u0628\u0627\u06cc\u0644","description":"\u062f\u0627\u0646\u0644\u0648\u062f \u0622\u0647\u0646\u06af \u067e\u06cc\u0634\u0648\u0627\u0632 \u0627\u06cc\u0631\u0627\u0646\u0633\u0644 \u0648 \u0647\u0645\u0631\u0627\u0647 \u0627\u0648\u0644 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e \u0645\u0627","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tarikhema.org\/pishvaz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"}]}},"_links":{"self":[{"href":"https:\/\/tarikhema.org\/pishvaz\/wp-json\/wp\/v2\/tags\/1721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tarikhema.org\/pishvaz\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tarikhema.org\/pishvaz\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tarikhema.org\/pishvaz\/wp-json\/wp\/v2\/posts?tags=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}